{"id":534,"date":"2026-03-18T15:55:44","date_gmt":"2026-03-18T15:55:44","guid":{"rendered":"https:\/\/chezpaullouis.com\/?post_type=product&#038;p=534"},"modified":"2026-08-21T11:22:07","modified_gmt":"2026-08-21T11:22:07","slug":"bonbon-maxi-ginger","status":"publish","type":"product","link":"https:\/\/chezpaullouis.com\/en\/product\/bonbon-maxi-ginger\/","title":{"rendered":"Maxi Ginger Candy"},"content":{"rendered":"<p><strong data-start=\"67\" data-end=\"89\">Maxi Ginger Candy<\/strong> est une friandise au gingembre intense, combinant chaleur et piquant pour une exp\u00e9rience gustative unique. Chaque bonbon offre une saveur relev\u00e9e et l\u00e9g\u00e8rement sucr\u00e9e qui stimule les papilles et procure une sensation revigorante. Id\u00e9al pour les amateurs de go\u00fbts forts et \u00e9pic\u00e9s, ce bonbon se savoure lentement pour profiter pleinement de son ar\u00f4me authentique et de son effet rafra\u00eechissant.<\/p>","protected":false},"excerpt":{"rendered":"<p><strong data-start=\"67\" data-end=\"89\">Maxi Ginger Candy<\/strong> est une friandise au gingembre intense, combinant chaleur et piquant pour une exp\u00e9rience gustative unique. Chaque bonbon offre une saveur relev\u00e9e et l\u00e9g\u00e8rement sucr\u00e9e qui stimule les papilles et procure une sensation revigorante. Id\u00e9al pour les amateurs de go\u00fbts forts et \u00e9pic\u00e9s, ce bonbon se savoure lentement pour profiter pleinement de son ar\u00f4me authentique et de son effet rafra\u00eechissant.<\/p>","protected":false},"featured_media":595,"comment_status":"open","ping_status":"closed","template":"","meta":{"_oliver_stock_2188":8,"_oliver_low_stock_2188":0,"_oliver_barcode":"","_oliver_pos_exclude":"no","_oliver_pos_fulfillment_instructions":"","_oliver_pos_prep_time":0,"_oliver_pos_fulfillment_category":"","_oliver_pos_prompt_notes":"no","_oliver_pos_kds_priority":"normal","_oliver_pos_fulfillment_image":0},"product_brand":[155],"product_cat":[172],"product_tag":[],"class_list":["post-534","product","type-product","status-publish","has-post-thumbnail","product_brand-maxi","product_cat-confisserie-snacks","first","onbackorder","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product\/534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/comments?post=534"}],"version-history":[{"count":2,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product\/534\/revisions"}],"predecessor-version":[{"id":2312,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product\/534\/revisions\/2312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/media\/595"}],"wp:attachment":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/media?parent=534"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product_brand?post=534"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product_cat?post=534"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product_tag?post=534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}