{"id":529,"date":"2026-03-18T15:45:51","date_gmt":"2026-03-18T15:45:51","guid":{"rendered":"https:\/\/chezpaullouis.com\/?post_type=product&#038;p=529"},"modified":"2026-05-04T17:11:07","modified_gmt":"2026-05-04T17:11:07","slug":"bonbon-fruity-lollipop","status":"publish","type":"product","link":"https:\/\/chezpaullouis.com\/en\/product\/bonbon-fruity-lollipop\/","title":{"rendered":"Fruity Lollipop"},"content":{"rendered":"<p><strong data-start=\"64\" data-end=\"83\">Fruity Lollipop<\/strong> est une sucette color\u00e9e et gourmande qui offre une explosion de saveurs fruit\u00e9es \u00e0 chaque bouch\u00e9e. Sa texture lisse et croquante fond lentement en bouche, r\u00e9v\u00e9lant des ar\u00f4mes sucr\u00e9s et acidul\u00e9s qui ravissent petits et grands. Parfait pour se faire plaisir ou partager, c\u2019est le bonbon id\u00e9al pour un moment de douceur fruit\u00e9e et de plaisir ludique.<\/p>","protected":false},"excerpt":{"rendered":"<p><strong data-start=\"64\" data-end=\"83\">Fruity Lollipop<\/strong> est une sucette color\u00e9e et gourmande qui offre une explosion de saveurs fruit\u00e9es \u00e0 chaque bouch\u00e9e. Sa texture lisse et croquante fond lentement en bouche, r\u00e9v\u00e9lant des ar\u00f4mes sucr\u00e9s et acidul\u00e9s qui ravissent petits et grands. Parfait pour se faire plaisir ou partager, c\u2019est le bonbon id\u00e9al pour un moment de douceur fruit\u00e9e et de plaisir ludique.<\/p>","protected":false},"featured_media":591,"comment_status":"open","ping_status":"closed","template":"","meta":{"_oliver_stock_2188":0,"_oliver_low_stock_2188":0,"_oliver_barcode":"","_oliver_pos_exclude":"no","_oliver_pos_fulfillment_instructions":"","_oliver_pos_prep_time":0,"_oliver_pos_fulfillment_category":"","_oliver_pos_prompt_notes":"no","_oliver_pos_kds_priority":"normal","_oliver_pos_fulfillment_image":0},"product_brand":[153],"product_cat":[172],"product_tag":[],"class_list":["post-529","product","type-product","status-publish","has-post-thumbnail","product_brand-lollipop","product_cat-confisserie-snacks","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product\/529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/comments?post=529"}],"version-history":[{"count":0,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product\/529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/media\/591"}],"wp:attachment":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/media?parent=529"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product_brand?post=529"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product_cat?post=529"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product_tag?post=529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}