{"id":1407,"date":"2026-05-07T15:53:05","date_gmt":"2026-05-07T15:53:05","guid":{"rendered":"https:\/\/chezpaullouis.com\/?post_type=product&#038;p=1407"},"modified":"2026-07-27T17:18:09","modified_gmt":"2026-07-27T17:18:09","slug":"redbull-2","status":"publish","type":"product","link":"https:\/\/chezpaullouis.com\/en\/product\/redbull-2\/","title":{"rendered":"Red Bull"},"content":{"rendered":"<p>Red Bull est une boisson \u00e9nerg\u00e9tique embl\u00e9matique, connue pour son effet stimulant et revitalisant. Lanc\u00e9e en 1987, cette boisson est con\u00e7ue pour augmenter l\u2019\u00e9nergie, am\u00e9liorer la concentration et favoriser la performance. Sa formule unique contient de la caf\u00e9ine, de la taurine, des vitamines B, et du sucre, ce qui lui permet de fournir un coup de fouet rapide pour affronter les journ\u00e9es charg\u00e9es ou les moments de fatigue.<\/p>\n<p>Red Bull est \u00e9galement c\u00e9l\u00e8bre pour son engagement dans le sport et l\u2019aventure, sponsorisant de nombreux \u00e9v\u00e9nements sportifs et athl\u00e8tes \u00e0 travers le monde. La boisson est souvent associ\u00e9e \u00e0 un style de vie dynamique et \u00e9nergique, et est disponible dans plusieurs variantes, dont des options sans sucre et des saveurs diff\u00e9rentes. Que ce soit pour une s\u00e9ance de sport, un long trajet ou simplement pour rester alerte, Red Bull est une option populaire pour ceux qui recherchent un regain d\u2019\u00e9nergie rapide.<\/p>","protected":false},"excerpt":{"rendered":"<p>Red Bull est une boisson \u00e9nerg\u00e9tique embl\u00e9matique, connue pour son effet stimulant et revitalisant. Lanc\u00e9e en 1987, cette boisson est con\u00e7ue pour augmenter l\u2019\u00e9nergie, am\u00e9liorer la concentration et favoriser la performance.<\/p>","protected":false},"featured_media":1996,"comment_status":"open","ping_status":"closed","template":"","meta":{"_oliver_stock_2188":1,"_oliver_low_stock_2188":0,"_oliver_barcode":"","_oliver_pos_exclude":"no","_oliver_pos_fulfillment_instructions":"","_oliver_pos_prep_time":0,"_oliver_pos_fulfillment_category":"","_oliver_pos_prompt_notes":"no","_oliver_pos_kds_priority":"normal","_oliver_pos_fulfillment_image":0},"product_brand":[187],"product_cat":[174],"product_tag":[],"class_list":["post-1407","product","type-product","status-publish","has-post-thumbnail","product_brand-redbull","product_cat-boissons-sans-alcool","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product\/1407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/comments?post=1407"}],"version-history":[{"count":3,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product\/1407\/revisions"}],"predecessor-version":[{"id":1998,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product\/1407\/revisions\/1998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/media\/1996"}],"wp:attachment":[{"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/media?parent=1407"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product_brand?post=1407"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product_cat?post=1407"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chezpaullouis.com\/en\/wp-json\/wp\/v2\/product_tag?post=1407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}